{"id":80263,"date":"2026-03-06T12:24:17","date_gmt":"2026-03-06T12:24:17","guid":{"rendered":"https:\/\/teeptrak.com\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/"},"modified":"2026-06-08T19:57:47","modified_gmt":"2026-06-08T19:57:47","slug":"comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento","status":"publish","type":"post","link":"https:\/\/teeptrak.com\/es\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/","title":{"rendered":"Comprender y mejorar el OEE y OOE para f\u00e1bricas de alto rendimiento"},"content":{"rendered":"<p>En la industria manufacturera, la competencia es feroz y los m\u00e1rgenes suelen ser ajustados. En este contexto, maximizar la eficiencia de cada equipo es clave para asegurar la rentabilidad y competitividad de una f\u00e1brica. Los t\u00e9rminos OEE, o eficiencia global de equipos, y OOE, eficiencia global de operaciones, surgen constantemente como palancas cr\u00edticas para alcanzar este objetivo. Estos indicadores permiten medir y analizar el desempe\u00f1o de los equipos, pero sin una comprensi\u00f3n clara y una aplicaci\u00f3n correcta, pueden dar lugar a cuellos de botella e ineficiencias que cuestan caro a las operaciones.<\/p>\n<p>Los problemas relacionados con un seguimiento deficiente o una interpretaci\u00f3n incorrecta del OEE y OOE son numerosos. Entre las causas comunes se encuentran la falta de datos precisos y en tiempo real, m\u00e9todos de c\u00e1lculo err\u00f3neos, y equipos no capacitados en su an\u00e1lisis. Estas deficiencias provocan aumentos de costos, p\u00e9rdidas de tiempo y reducci\u00f3n de la calidad. Un OEE deficiente a menudo resulta de la incapacidad para identificar y resolver las fuentes de tiempo de inactividad o desperdicio, lo que afecta directamente al TRS y, por lo tanto, a la rentabilidad. Para los responsables industriales, estos impactos se traducen en decisiones basadas en datos incompletos o incorrectos, comprometiendo la estrategia general de la empresa.<\/p>\n<p>Para remediar estos problemas, se pueden implementar varias soluciones. Un buen punto de partida es implantar sistemas de seguimiento y an\u00e1lisis de desempe\u00f1o en tiempo real, como los que ofrece TeepTrak, que permiten recopilar datos precisos y confiables de todos los equipos. La implementaci\u00f3n de una estrategia de mejora continua tambi\u00e9n requiere capacitaci\u00f3n rigurosa de los equipos en la interpretaci\u00f3n del OEE y el uso de indicadores relevantes para dirigirse a \u00e1reas espec\u00edficas de mejora. Adem\u00e1s, la digitalizaci\u00f3n del taller de producci\u00f3n, como la soluci\u00f3n OEE y <a href=\"https:\/\/teeptrak.com\/fr\/\">seguimiento de desempe\u00f1o en tiempo real<\/a> de TeepTrak, juega un papel esencial en la recopilaci\u00f3n de datos precisos y procesables. Finalmente, es crucial integrar metodolog\u00edas de an\u00e1lisis como AMFE o Lean Manufacturing para lograr ganancias de productividad sostenibles.<\/p>\n<p>Un ejemplo concreto ilustra bien la eficiencia: una f\u00e1brica de producci\u00f3n de componentes electr\u00f3nicos que enfrentaba interrupciones regulares integr\u00f3 un sistema de seguimiento TRS\/OEE de TeepTrak. Al analizar los tiempos de parada con precisi\u00f3n, la empresa pudo identificar que una m\u00e1quina espec\u00edfica presentaba una tasa de falla anormalmente alta en los mismos horarios cada semana. Gracias a datos en tiempo real, los equipos ajustaron sus cronogramas de mantenimiento, reduciendo los tiempos de parada en un 30% e mejorando significativamente el OEE global de la f\u00e1brica.<\/p>\n<p>En conclusi\u00f3n, la implementaci\u00f3n de un sistema de medici\u00f3n y an\u00e1lisis del OEE y OOE es indispensable para mejorar la productividad de las l\u00edneas de producci\u00f3n. Un proyecto estructurado de seguimiento TRS\/OEE no solo permite optimizar las operaciones existentes, sino tambi\u00e9n anticipar mejor las inversiones futuras gracias a una visibilidad clara del desempe\u00f1o. Para pasar a la acci\u00f3n, se recomienda adoptar soluciones como las de <a href=\"https:\/\/teeptrak.com\/fr\/nos-solutions\/\">TeepTrak<\/a>, declarar sus prioridades estrat\u00e9gicas e involucrar a los equipos con herramientas adecuadas para apuntar a la excelencia operacional.<\/p>\n<h3><strong>FAQ<\/strong><\/h3>\n<h4><strong>Pregunta 1: \u00bfC\u00f3mo calcular con precisi\u00f3n el OEE?<\/strong><\/h4>\n<p>El OEE se calcula multiplicando tres factores: disponibilidad, desempe\u00f1o y calidad. Cada factor representa una parte cr\u00edtica de la eficiencia general. Aseg\u00farese de recopilar datos precisos sobre paradas, velocidad de producci\u00f3n y calidad del producto terminado para un c\u00e1lculo confiable.<\/p>\n<h4><strong>Pregunta 2: \u00bfCu\u00e1l es el impacto de un OEE deficiente en una f\u00e1brica?<\/strong><\/h4>\n<p>Un OEE deficiente puede resultar en costos de producci\u00f3n m\u00e1s altos, calidad reducida y tiempos de parada frecuentes. Estos aspectos afectan la rentabilidad general de la f\u00e1brica y pueden perjudicar la competitividad en el mercado.<\/p>\n<h4><strong>Pregunta 3: \u00bfPor d\u00f3nde empezar para mejorar el OEE?<\/strong><\/h4>\n<p>Comience por identificar las principales causas de ineficiencia mediante un an\u00e1lisis detallado del OEE. Involucre a sus equipos en la resoluci\u00f3n de estas causas e implemente soluciones de seguimiento en tiempo real para evaluar la efectividad de las mejoras realizadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubra c\u00f3mo comprender y mejorar el OEE para optimizar el desempe\u00f1o de sus l\u00edneas de producci\u00f3n e incrementar su competitividad.<\/p>\n","protected":false},"author":384731,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","ai_seo_title":"OEE y OOE para f\u00e1bricas | TeepTrak","ai_meta_description":"Mejora el OEE y OOE de tu f\u00e1brica con estrategias efectivas. Aprende a optimizar rendimiento y eficiencia operacional para m\u00e1xima productividad.","ai_focus_keyword":"OEE OOE f\u00e1bricas","footnotes":""},"categories":[10],"tags":[],"class_list":["post-80263","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OEE y OOE para f\u00e1bricas | TeepTrak<\/title>\n<meta name=\"description\" content=\"Mejora el OEE y OOE de tu f\u00e1brica con estrategias efectivas. Aprende a optimizar rendimiento y eficiencia operacional para m\u00e1xima productividad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teeptrak.com\/es\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OEE y OOE para f\u00e1bricas | TeepTrak\" \/>\n<meta property=\"og:description\" content=\"Mejora el OEE y OOE de tu f\u00e1brica con estrategias efectivas. Aprende a optimizar rendimiento y eficiencia operacional para m\u00e1xima productividad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teeptrak.com\/es\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"TEEPTRAK\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-06T12:24:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T19:57:47+00:00\" \/>\n<meta name=\"author\" content=\"Ravinder Singh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ravinder Singh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\\\/\"},\"author\":{\"name\":\"Ravinder Singh\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/#\\\/schema\\\/person\\\/04395f9a2aa972ad0105f0c9f2e3fca3\"},\"headline\":\"Comprender y mejorar el OEE y OOE para f\u00e1bricas de alto rendimiento\",\"datePublished\":\"2026-03-06T12:24:17+00:00\",\"dateModified\":\"2026-06-08T19:57:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\\\/\"},\"wordCount\":718,\"publisher\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/#organization\"},\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\\\/\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\\\/\",\"name\":\"OEE y OOE para f\u00e1bricas | TeepTrak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/#website\"},\"datePublished\":\"2026-03-06T12:24:17+00:00\",\"dateModified\":\"2026-06-08T19:57:47+00:00\",\"description\":\"Mejora el OEE y OOE de tu f\u00e1brica con estrategias efectivas. Aprende a optimizar rendimiento y eficiencia operacional para m\u00e1xima productividad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/teeptrak.com\\\/es\\\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/nueva-pagina-de-casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comprender y mejorar el OEE y OOE para f\u00e1bricas de alto rendimiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/\",\"name\":\"TEEPTRAK\",\"description\":\"Optimisez votre potentiel industriel\",\"publisher\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/#organization\",\"name\":\"TEEPTRAK\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Capture-decran-2023-05-04-112832.png\",\"contentUrl\":\"https:\\\/\\\/teeptrak.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Capture-decran-2023-05-04-112832.png\",\"width\":512,\"height\":512,\"caption\":\"TEEPTRAK\"},\"image\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/teeptrak\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/teeptrakinternational\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/#\\\/schema\\\/person\\\/04395f9a2aa972ad0105f0c9f2e3fca3\",\"name\":\"Ravinder Singh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g\",\"caption\":\"Ravinder Singh\"},\"url\":\"https:\\\/\\\/teeptrak.com\\\/es\\\/author\\\/ravinder-teeptrak\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OEE y OOE para f\u00e1bricas | TeepTrak","description":"Mejora el OEE y OOE de tu f\u00e1brica con estrategias efectivas. Aprende a optimizar rendimiento y eficiencia operacional para m\u00e1xima productividad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teeptrak.com\/es\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/","og_locale":"es_ES","og_type":"article","og_title":"OEE y OOE para f\u00e1bricas | TeepTrak","og_description":"Mejora el OEE y OOE de tu f\u00e1brica con estrategias efectivas. Aprende a optimizar rendimiento y eficiencia operacional para m\u00e1xima productividad.","og_url":"https:\/\/teeptrak.com\/es\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/","og_site_name":"TEEPTRAK","article_published_time":"2026-03-06T12:24:17+00:00","article_modified_time":"2026-06-08T19:57:47+00:00","author":"Ravinder Singh","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ravinder Singh","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/teeptrak.com\/es\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/#article","isPartOf":{"@id":"https:\/\/teeptrak.com\/es\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/"},"author":{"name":"Ravinder Singh","@id":"https:\/\/teeptrak.com\/es\/#\/schema\/person\/04395f9a2aa972ad0105f0c9f2e3fca3"},"headline":"Comprender y mejorar el OEE y OOE para f\u00e1bricas de alto rendimiento","datePublished":"2026-03-06T12:24:17+00:00","dateModified":"2026-06-08T19:57:47+00:00","mainEntityOfPage":{"@id":"https:\/\/teeptrak.com\/es\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/"},"wordCount":718,"publisher":{"@id":"https:\/\/teeptrak.com\/es\/#organization"},"articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/teeptrak.com\/es\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/","url":"https:\/\/teeptrak.com\/es\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/","name":"OEE y OOE para f\u00e1bricas | TeepTrak","isPartOf":{"@id":"https:\/\/teeptrak.com\/es\/#website"},"datePublished":"2026-03-06T12:24:17+00:00","dateModified":"2026-06-08T19:57:47+00:00","description":"Mejora el OEE y OOE de tu f\u00e1brica con estrategias efectivas. Aprende a optimizar rendimiento y eficiencia operacional para m\u00e1xima productividad.","breadcrumb":{"@id":"https:\/\/teeptrak.com\/es\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teeptrak.com\/es\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/teeptrak.com\/es\/comprender-y-mejorar-el-oee-y-ooe-para-fabricas-de-alto-rendimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/teeptrak.com\/es\/nueva-pagina-de-casa\/"},{"@type":"ListItem","position":2,"name":"Comprender y mejorar el OEE y OOE para f\u00e1bricas de alto rendimiento"}]},{"@type":"WebSite","@id":"https:\/\/teeptrak.com\/es\/#website","url":"https:\/\/teeptrak.com\/es\/","name":"TEEPTRAK","description":"Optimisez votre potentiel industriel","publisher":{"@id":"https:\/\/teeptrak.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teeptrak.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/teeptrak.com\/es\/#organization","name":"TEEPTRAK","url":"https:\/\/teeptrak.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/teeptrak.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/teeptrak.com\/wp-content\/uploads\/2023\/05\/cropped-Capture-decran-2023-05-04-112832.png","contentUrl":"https:\/\/teeptrak.com\/wp-content\/uploads\/2023\/05\/cropped-Capture-decran-2023-05-04-112832.png","width":512,"height":512,"caption":"TEEPTRAK"},"image":{"@id":"https:\/\/teeptrak.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/teeptrak\/","https:\/\/www.linkedin.com\/company\/teeptrakinternational\/"]},{"@type":"Person","@id":"https:\/\/teeptrak.com\/es\/#\/schema\/person\/04395f9a2aa972ad0105f0c9f2e3fca3","name":"Ravinder Singh","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g","caption":"Ravinder Singh"},"url":"https:\/\/teeptrak.com\/es\/author\/ravinder-teeptrak\/"}]}},"_links":{"self":[{"href":"https:\/\/teeptrak.com\/es\/wp-json\/wp\/v2\/posts\/80263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teeptrak.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teeptrak.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teeptrak.com\/es\/wp-json\/wp\/v2\/users\/384731"}],"replies":[{"embeddable":true,"href":"https:\/\/teeptrak.com\/es\/wp-json\/wp\/v2\/comments?post=80263"}],"version-history":[{"count":1,"href":"https:\/\/teeptrak.com\/es\/wp-json\/wp\/v2\/posts\/80263\/revisions"}],"predecessor-version":[{"id":104483,"href":"https:\/\/teeptrak.com\/es\/wp-json\/wp\/v2\/posts\/80263\/revisions\/104483"}],"wp:attachment":[{"href":"https:\/\/teeptrak.com\/es\/wp-json\/wp\/v2\/media?parent=80263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teeptrak.com\/es\/wp-json\/wp\/v2\/categories?post=80263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teeptrak.com\/es\/wp-json\/wp\/v2\/tags?post=80263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}