{"id":80678,"date":"2026-03-06T12:39:47","date_gmt":"2026-03-06T12:39:47","guid":{"rendered":"https:\/\/teeptrak.com\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/"},"modified":"2026-06-08T17:00:40","modified_gmt":"2026-06-08T17:00:40","slug":"betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung","status":"publish","type":"post","link":"https:\/\/teeptrak.com\/de\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/","title":{"rendered":"Betriebliche Exzellenz mit OEE: Maximieren Sie Ihre industrielle Leistung"},"content":{"rendered":"<p>Im Kontext gestiegener Wettbewerbsf\u00e4higkeit und Margendruck m\u00fcssen Fertigungsunternehmen ihre Prozesse regelm\u00e4\u00dfig optimieren, um ein hohes Leistungsniveau zu halten. Ein wesentlicher Hebel dieser Optimierung ist die Gesamtanlageneffektivit\u00e4t (OEE), eine Schl\u00fcsselkennzahl zur Bewertung und Verbesserung der Betriebsleistung. OEE oder <a href=\"https:\/\/en.wikipedia.org\/wiki\/Overall_equipment_effectiveness\">Overall Equipment Effectiveness<\/a> ist entscheidend, da es einen umfassenden \u00dcberblick \u00fcber Verf\u00fcgbarkeit, Leistung und Produktionsqualit\u00e4t bietet. Viele Fabriken erreichen ihr Potenzial jedoch nicht, da die Berechnung komplex ist oder zuverl\u00e4ssige Echtzeitdaten fehlen.<\/p>\n<p>Der Mangel an strenger OEE-\u00dcberwachung hat oft mehrere Ursachen. Zun\u00e4chst verf\u00fcgen viele Unternehmen nicht \u00fcber ein wirksames Datenerfassungs- und Analysesystem, das ihre F\u00e4higkeit, Ineffizienzen zu erkennen, einschr\u00e4nkt. Dar\u00fcber hinaus f\u00fchren ungeplante Ausfallzeiten, Qualit\u00e4tsm\u00e4ngel und suboptimale Produktionszyklen zu erheblichen Verlusten und senken damit die Gesamtleistung. Die Auswirkungen sind erheblich auf Produktivit\u00e4t, Produktionskosten und letztendlich auf Rentabilit\u00e4t. Ohne genaues und echtzeitgest\u00fctztes TRS-Verst\u00e4ndnis ist es schwierig, wirksame Korrekturma\u00dfnahmen zu ergreifen.<\/p>\n<p>Gl\u00fccklicherweise gibt es klare Hebel zur Verbesserung dieser Situation. Die Digitalisierung der Shopfloor-Ebene mit L\u00f6sungen wie denen von <a href=\"https:\/\/teeptrak.com\/fr\/nos-solutions\/\">TeepTrak<\/a> erm\u00f6glicht die Echtzeit\u00fcberwachung der Leistung und die Umsetzung kontinuierlicher Verbesserungsstrategien. Es ist auch wichtig, Teams im Umgang mit diesen Tools zu schulen und klare, messbare Leistungsindikatoren zu definieren, um die OEE-Entwicklung zu verfolgen. Ein strukturierter Ansatz mit regelm\u00e4\u00dfigen Deming-Zyklen (Plan-Do-Check-Act) kann eine Werkstatt in eine agile und reaktive Produktionseinheit umwandeln.<\/p>\n<p>Ein konkretes Beispiel ist eine Elektronikkomponentenfabrik, die ein umfassendes OEE-\u00dcberwachungssystem mit TeepTrak implementiert hat. Zun\u00e4chst \u00fcberwachte die Fabrik ihre Leistung nur vage durch monatliche Audits. Durch die Installation einer echtzeitgest\u00fctzten TRS-\u00dcberwachung konnte die Fabrik h\u00e4ufige Ausfallzeiten aufgrund von Wartungsproblemen erkennen. Innerhalb von weniger als sechs Monaten f\u00fchrte die systematische Prozessverbesserung zu einer Steigerung des TRS um 20 %, wodurch Ausfallzeiten reduziert und die Produktionskapazit\u00e4t erheblich erh\u00f6ht wurden.<\/p>\n<p>F\u00fcr Industrieunternehmen, die ihre Leistung maximieren m\u00f6chten, ist es wichtig, mit einer genauen Diagnose der aktuellen OEE zu beginnen. Die Einf\u00fchrung innovativer L\u00f6sungen wie die von TeepTrak erm\u00f6glicht einen Sprung zur betrieblichen Exzellenz. Definieren Sie Ihre Ziele, messen Sie regelm\u00e4\u00dfig Ihre Fortschritte und nutzen Sie neue Technologien zur Prozessoptimierung. Das Effizienz-, Produktivit\u00e4ts- und Reaktivit\u00e4tssteigerungspotenzial ist immens, und die Strukturierung eines OEE-Projekts kann f\u00fcr den nachhaltigen Erfolg Ihres Unternehmens entscheidend sein.<\/p>\n<h3><strong>H\u00e4ufig gestellte Fragen<\/strong><\/h3>\n<h4><strong>Frage 1: Wie tr\u00e4gt OEE zur betrieblichen Exzellenz bei?<\/strong><\/h4>\n<p>OEE ist eine Schl\u00fcsselkennzahl, die Verf\u00fcgbarkeit, Leistung und Qualit\u00e4t Ihrer Ausr\u00fcstung misst. Durch die Optimierung dieser Parameter erreichen Sie eine bessere Gesamteffizienz und damit erh\u00f6hte betriebliche Exzellenz.<\/p>\n<h4><strong>Frage 2: Welche Auswirkungen hat eine schlechte OEE-Verwaltung?<\/strong><\/h4>\n<p>Eine ineffektive OEE-Verwaltung kann zu verborgenen Ineffizienzen, hohen Produktionskosten und verminderter Rentabilit\u00e4t f\u00fchren. Nicht identifizierte wiederkehrende Probleme beeinflussen direkt den TRS und damit die allgemeine Produktivit\u00e4t.<\/p>\n<h4><strong>Frage 3: Wo sollten Sie mit der OEE-Verbesserung beginnen?<\/strong><\/h4>\n<p>Beginnen Sie mit der Bewertung Ihrer aktuellen Indikatoren, identifizieren Sie Schwachstellen und implementieren Sie ein Echtzeit\u00fcberwachungssystem wie die von TeepTrak angebotenen. Schulen Sie Ihre Teams und \u00fcberwachen Sie regelm\u00e4\u00dfig Ihre Leistung, um Korrekturma\u00dfnahmen zu etablieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entdecken Sie betriebliche Exzellenz mit OEE durch klare Erkl\u00e4rungen, Beispiele und praktische Tipps zur Verbesserung der Leistung auf Ihren Produktionslinien.<\/p>\n","protected":false},"author":384731,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","ai_seo_title":"OEE Leistung maximieren | TeepTrak","ai_meta_description":"Steigern Sie Ihre industrielle Leistung mit OEE. Erfahren Sie, wie Sie betriebliche Exzellenz erreichen und Produktivit\u00e4t optimieren.","ai_focus_keyword":"OEE industrielle Leistung","footnotes":""},"categories":[7],"tags":[],"class_list":["post-80678","post","type-post","status-publish","format-standard","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OEE Leistung maximieren | TeepTrak<\/title>\n<meta name=\"description\" content=\"Steigern Sie Ihre industrielle Leistung mit OEE. Erfahren Sie, wie Sie betriebliche Exzellenz erreichen und Produktivit\u00e4t optimieren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teeptrak.com\/de\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OEE Leistung maximieren | TeepTrak\" \/>\n<meta property=\"og:description\" content=\"Steigern Sie Ihre industrielle Leistung mit OEE. Erfahren Sie, wie Sie betriebliche Exzellenz erreichen und Produktivit\u00e4t optimieren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teeptrak.com\/de\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/\" \/>\n<meta property=\"og:site_name\" content=\"TEEPTRAK - Connect to your industrial potential\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-06T12:39:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T17:00:40+00:00\" \/>\n<meta name=\"author\" content=\"Ravinder Singh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ravinder Singh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\\\/\"},\"author\":{\"name\":\"Ravinder Singh\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#\\\/schema\\\/person\\\/04395f9a2aa972ad0105f0c9f2e3fca3\"},\"headline\":\"Betriebliche Exzellenz mit OEE: Maximieren Sie Ihre industrielle Leistung\",\"datePublished\":\"2026-03-06T12:39:47+00:00\",\"dateModified\":\"2026-06-08T17:00:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\\\/\"},\"wordCount\":520,\"publisher\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#organization\"},\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\\\/\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\\\/\",\"name\":\"OEE Leistung maximieren | TeepTrak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#website\"},\"datePublished\":\"2026-03-06T12:39:47+00:00\",\"dateModified\":\"2026-06-08T17:00:40+00:00\",\"description\":\"Steigern Sie Ihre industrielle Leistung mit OEE. Erfahren Sie, wie Sie betriebliche Exzellenz erreichen und Produktivit\u00e4t optimieren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/teeptrak.com\\\/de\\\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/nouvelle-page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Betriebliche Exzellenz mit OEE: Maximieren Sie Ihre industrielle Leistung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/\",\"name\":\"TEEPTRAK\",\"description\":\"Optimisez votre potentiel industriel\",\"publisher\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#organization\",\"name\":\"TEEPTRAK\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Capture-decran-2023-05-04-112832.png\",\"contentUrl\":\"https:\\\/\\\/teeptrak.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Capture-decran-2023-05-04-112832.png\",\"width\":512,\"height\":512,\"caption\":\"TEEPTRAK\"},\"image\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/teeptrak\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/teeptrakinternational\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#\\\/schema\\\/person\\\/04395f9a2aa972ad0105f0c9f2e3fca3\",\"name\":\"Ravinder Singh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g\",\"caption\":\"Ravinder Singh\"},\"url\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/author\\\/ravinder-teeptrak\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OEE Leistung maximieren | TeepTrak","description":"Steigern Sie Ihre industrielle Leistung mit OEE. Erfahren Sie, wie Sie betriebliche Exzellenz erreichen und Produktivit\u00e4t optimieren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teeptrak.com\/de\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/","og_locale":"de_DE","og_type":"article","og_title":"OEE Leistung maximieren | TeepTrak","og_description":"Steigern Sie Ihre industrielle Leistung mit OEE. Erfahren Sie, wie Sie betriebliche Exzellenz erreichen und Produktivit\u00e4t optimieren.","og_url":"https:\/\/teeptrak.com\/de\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/","og_site_name":"TEEPTRAK - Connect to your industrial potential","article_published_time":"2026-03-06T12:39:47+00:00","article_modified_time":"2026-06-08T17:00:40+00:00","author":"Ravinder Singh","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Ravinder Singh","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/teeptrak.com\/de\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/#article","isPartOf":{"@id":"https:\/\/teeptrak.com\/de\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/"},"author":{"name":"Ravinder Singh","@id":"https:\/\/teeptrak.com\/de\/#\/schema\/person\/04395f9a2aa972ad0105f0c9f2e3fca3"},"headline":"Betriebliche Exzellenz mit OEE: Maximieren Sie Ihre industrielle Leistung","datePublished":"2026-03-06T12:39:47+00:00","dateModified":"2026-06-08T17:00:40+00:00","mainEntityOfPage":{"@id":"https:\/\/teeptrak.com\/de\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/"},"wordCount":520,"publisher":{"@id":"https:\/\/teeptrak.com\/de\/#organization"},"articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/teeptrak.com\/de\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/","url":"https:\/\/teeptrak.com\/de\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/","name":"OEE Leistung maximieren | TeepTrak","isPartOf":{"@id":"https:\/\/teeptrak.com\/de\/#website"},"datePublished":"2026-03-06T12:39:47+00:00","dateModified":"2026-06-08T17:00:40+00:00","description":"Steigern Sie Ihre industrielle Leistung mit OEE. Erfahren Sie, wie Sie betriebliche Exzellenz erreichen und Produktivit\u00e4t optimieren.","breadcrumb":{"@id":"https:\/\/teeptrak.com\/de\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teeptrak.com\/de\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/teeptrak.com\/de\/betriebliche-exzellenz-mit-oee-maximieren-sie-ihre-industrielle-leistung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/teeptrak.com\/de\/nouvelle-page-daccueil\/"},{"@type":"ListItem","position":2,"name":"Betriebliche Exzellenz mit OEE: Maximieren Sie Ihre industrielle Leistung"}]},{"@type":"WebSite","@id":"https:\/\/teeptrak.com\/de\/#website","url":"https:\/\/teeptrak.com\/de\/","name":"TEEPTRAK","description":"Optimisez votre potentiel industriel","publisher":{"@id":"https:\/\/teeptrak.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teeptrak.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/teeptrak.com\/de\/#organization","name":"TEEPTRAK","url":"https:\/\/teeptrak.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/teeptrak.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/teeptrak.com\/wp-content\/uploads\/2023\/05\/cropped-Capture-decran-2023-05-04-112832.png","contentUrl":"https:\/\/teeptrak.com\/wp-content\/uploads\/2023\/05\/cropped-Capture-decran-2023-05-04-112832.png","width":512,"height":512,"caption":"TEEPTRAK"},"image":{"@id":"https:\/\/teeptrak.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/teeptrak\/","https:\/\/www.linkedin.com\/company\/teeptrakinternational\/"]},{"@type":"Person","@id":"https:\/\/teeptrak.com\/de\/#\/schema\/person\/04395f9a2aa972ad0105f0c9f2e3fca3","name":"Ravinder Singh","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g","caption":"Ravinder Singh"},"url":"https:\/\/teeptrak.com\/de\/author\/ravinder-teeptrak\/"}]}},"_links":{"self":[{"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/posts\/80678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/users\/384731"}],"replies":[{"embeddable":true,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/comments?post=80678"}],"version-history":[{"count":1,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/posts\/80678\/revisions"}],"predecessor-version":[{"id":102490,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/posts\/80678\/revisions\/102490"}],"wp:attachment":[{"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/media?parent=80678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/categories?post=80678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/tags?post=80678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}