{"id":80234,"date":"2026-03-06T12:24:13","date_gmt":"2026-03-06T12:24:13","guid":{"rendered":"https:\/\/teeptrak.com\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/"},"modified":"2026-06-08T17:06:44","modified_gmt":"2026-06-08T17:06:44","slug":"verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz","status":"publish","type":"post","link":"https:\/\/teeptrak.com\/de\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/","title":{"rendered":"Verstehen Sie &lsquo;OEE Glass vs OEM&rsquo; zur Verbesserung der Industrieeffizienz"},"content":{"rendered":"<p>Im aktuellen Industriekontext ist kontinuierliche Verbesserung entscheidend f\u00fcr die Aufrechterhaltung der Wettbewerbsf\u00e4higkeit. Das Verst\u00e4ndnis des Unterschieds zwischen &lsquo;OEE Glass vs OEM&rsquo; ist wesentlich, um das Leistungspotenzial von Anlagen richtig zu nutzen. Auf der Grundlage der Overall Equipment Effectiveness (OEE), einem Schl\u00fcsselleistungsindikator, k\u00f6nnen Industriebetriebe L\u00fccken zwischen tats\u00e4chlicher und theoretischer Leistung von Ausr\u00fcstungen identifizieren und schlie\u00dfen. F\u00fcr Fabrikleiter und Industrieleistungsteams erm\u00f6glicht die Beherrschung dieser Konzepte die Ausrichtung erforderlicher Korrekturma\u00dfnahmen zur Verbesserung der Produktivit\u00e4t und Kostenreduzierung.<\/p>\n<p>Die Ursachen f\u00fcr schwache Leistung in Bezug auf &lsquo;OEE Glass vs OEM&rsquo; sind oft multifaktoriell. Unkenntnis der tats\u00e4chlichen Anlagenkapazit\u00e4ten, ungeplante Ausfallzeiten und M\u00e4ngel sind gro\u00dfe Hindernisse f\u00fcr die Optimierung. Diese Faktoren wirken sich direkt auf TRS\/OEE aus und k\u00f6nnen die Produktionskosten erh\u00f6hen. Dar\u00fcber hinaus verhindert die Vernachl\u00e4ssigung detaillierter Analysemethoden und Echtzeit\u00fcberwachung der Leistung eine genaue Transparenz der Produktionsvorg\u00e4nge.<\/p>\n<p>Um diese Herausforderungen zu bew\u00e4ltigen, ist es zwingend erforderlich, Echtzeit\u00fcberwachungs- und Analysel\u00f6sungen zu integrieren, wie sie von <a href=\"https:\/\/teeptrak.com\/fr\/\">TeepTrak<\/a> angeboten werden. Der Ansatz umfasst die Verwendung von Digitalisierungswerkzeugen zum Erfassen, Analysieren und Visualisieren von Produktionsdaten. Die Implementierung von Leistungsindikatoren wie der Gesamtanlageneffektivit\u00e4t (TRS) ist ebenfalls entscheidend. Lean-Methoden und Total Productive Maintenance (TPM) k\u00f6nnen kombiniert werden, um Verschwendung zu beseitigen, die Verf\u00fcgbarkeit von Anlagen zu verbessern und die Produktqualit\u00e4t zu steigern.<\/p>\n<p>Ein typischer Anwendungsfall ist eine Glash\u00fctte, die das OEE auf ihren Produktionslinien verbessern wollte. Nach der Implementierung einer TeepTrak-Echtzeit\u00fcberwachungsl\u00f6sung konnte die Fabrik die Ausfallzeiten um 20 % reduzieren, indem Engp\u00e4sse erkannt und die vorbeugende Wartung optimiert wurden. Die erh\u00f6hte Transparenz erm\u00f6glichte es den Teams, schnell auf Zwischenf\u00e4lle zu reagieren und damit ihr TRS erheblich zu verbessern.<\/p>\n<p>Zusammenfassend l\u00e4sst sich sagen, dass die Beherrschung von &lsquo;OEE Glass vs OEM&rsquo; und die Implementierung fortschrittlicher \u00dcberwachungswerkzeuge wie die von TeepTrak angebotenen die Industrieleistung transformieren k\u00f6nnen. Es wird empfohlen, mit einer gr\u00fcndlichen Analyse Ihres aktuellen OEE zu beginnen, klare Ziele zu setzen und einen strukturierten Plan f\u00fcr kontinuierliche Verbesserung zu entwickeln. Die Gewinne in Produktivit\u00e4t, Qualit\u00e4t und Betriebskostenreduktion rechtfertigen vollst\u00e4ndig eine solche Investition. <a href=\"https:\/\/teeptrak.com\/fr\/\">TeepTrak-L\u00f6sungen zur Digitalisierung Ihrer Produktion<\/a> stehen zur Verf\u00fcgung, um Sie bei diesem Vorhaben zu unterst\u00fctzen.<\/p>\n<h3><strong>FAQ<\/strong><\/h3>\n<h4><strong>Frage 1: Wie kann ich mein OEE in einer komplexen Industrieumgebung verbessern?<\/strong><\/h4>\n<p>Um das OEE zu verbessern, beginnen Sie mit der Analyse vorhandener Produktionsdaten, identifizieren Sie Verluste und integrieren Sie Echtzeit\u00fcberwachungssysteme wie TeepTrak, um die Leistungen effizienter zu verfolgen.<\/p>\n<h4><strong>Frage 2: Welche sind die wichtigsten Hebel zur Reduzierung von Ausfallzeiten?<\/strong><\/h4>\n<p>Die Reduzierung von Ausfallzeiten erfordert die Implementierung vorbeugender Wartungsprogramme, die Verbesserung der Schulung von Bedienern und den Einsatz fortgeschrittener Diagnosewerkzeuge, um Engp\u00e4sse schnell zu erkennen und zu beheben.<\/p>\n<h4><strong>Frage 3: Wo beginne ich mit einem kontinuierlichen Verbesserungsprojekt auf OEE-Basis?<\/strong><\/h4>\n<p>Beginnen Sie mit einem Audit der aktuellen Leistungen, setzen Sie spezifische Ziele f\u00fcr TRS\/OEE und implementieren Sie Analyse- und Monitoring-Tools, um die Transparenz Ihrer Produktionsvorg\u00e4nge zu verbessern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erfahren Sie, wie &lsquo;OEE Glass vs OEM&rsquo; die Leistung Ihrer Produktionslinien beeinflussen kann und wie Sie Ihr TRS\/OEE verbessern.<\/p>\n","protected":false},"author":384731,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","ai_seo_title":"OEE Glass vs OEM | TeepTrak","ai_meta_description":"Erfahren Sie den Unterschied zwischen OEE Glass und OEM. Optimieren Sie Ihre Industrieeffizienz mit praktischen Insights und bew\u00e4hrten Strategien.","ai_focus_keyword":"OEE Glass OEM Unterschied","footnotes":""},"categories":[7],"tags":[],"class_list":["post-80234","post","type-post","status-publish","format-standard","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OEE Glass vs OEM | TeepTrak<\/title>\n<meta name=\"description\" content=\"Erfahren Sie den Unterschied zwischen OEE Glass und OEM. Optimieren Sie Ihre Industrieeffizienz mit praktischen Insights und bew\u00e4hrten Strategien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teeptrak.com\/de\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OEE Glass vs OEM | TeepTrak\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie den Unterschied zwischen OEE Glass und OEM. Optimieren Sie Ihre Industrieeffizienz mit praktischen Insights und bew\u00e4hrten Strategien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teeptrak.com\/de\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/\" \/>\n<meta property=\"og:site_name\" content=\"TEEPTRAK - Connect to your industrial potential\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-06T12:24:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T17:06:44+00:00\" \/>\n<meta name=\"author\" content=\"Ravinder Singh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ravinder Singh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\\\/\"},\"author\":{\"name\":\"Ravinder Singh\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#\\\/schema\\\/person\\\/04395f9a2aa972ad0105f0c9f2e3fca3\"},\"headline\":\"Verstehen Sie &lsquo;OEE Glass vs OEM&rsquo; zur Verbesserung der Industrieeffizienz\",\"datePublished\":\"2026-03-06T12:24:13+00:00\",\"dateModified\":\"2026-06-08T17:06:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\\\/\"},\"wordCount\":519,\"publisher\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#organization\"},\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\\\/\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\\\/\",\"name\":\"OEE Glass vs OEM | TeepTrak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#website\"},\"datePublished\":\"2026-03-06T12:24:13+00:00\",\"dateModified\":\"2026-06-08T17:06:44+00:00\",\"description\":\"Erfahren Sie den Unterschied zwischen OEE Glass und OEM. Optimieren Sie Ihre Industrieeffizienz mit praktischen Insights und bew\u00e4hrten Strategien.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/teeptrak.com\\\/de\\\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/nouvelle-page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verstehen Sie &lsquo;OEE Glass vs OEM&rsquo; zur Verbesserung der Industrieeffizienz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/\",\"name\":\"TEEPTRAK\",\"description\":\"Optimisez votre potentiel industriel\",\"publisher\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#organization\",\"name\":\"TEEPTRAK\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Capture-decran-2023-05-04-112832.png\",\"contentUrl\":\"https:\\\/\\\/teeptrak.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-Capture-decran-2023-05-04-112832.png\",\"width\":512,\"height\":512,\"caption\":\"TEEPTRAK\"},\"image\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/teeptrak\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/teeptrakinternational\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#\\\/schema\\\/person\\\/04395f9a2aa972ad0105f0c9f2e3fca3\",\"name\":\"Ravinder Singh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g\",\"caption\":\"Ravinder Singh\"},\"url\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/author\\\/ravinder-teeptrak\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OEE Glass vs OEM | TeepTrak","description":"Erfahren Sie den Unterschied zwischen OEE Glass und OEM. Optimieren Sie Ihre Industrieeffizienz mit praktischen Insights und bew\u00e4hrten Strategien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teeptrak.com\/de\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/","og_locale":"de_DE","og_type":"article","og_title":"OEE Glass vs OEM | TeepTrak","og_description":"Erfahren Sie den Unterschied zwischen OEE Glass und OEM. Optimieren Sie Ihre Industrieeffizienz mit praktischen Insights und bew\u00e4hrten Strategien.","og_url":"https:\/\/teeptrak.com\/de\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/","og_site_name":"TEEPTRAK - Connect to your industrial potential","article_published_time":"2026-03-06T12:24:13+00:00","article_modified_time":"2026-06-08T17:06:44+00:00","author":"Ravinder Singh","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Ravinder Singh","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/teeptrak.com\/de\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/#article","isPartOf":{"@id":"https:\/\/teeptrak.com\/de\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/"},"author":{"name":"Ravinder Singh","@id":"https:\/\/teeptrak.com\/de\/#\/schema\/person\/04395f9a2aa972ad0105f0c9f2e3fca3"},"headline":"Verstehen Sie &lsquo;OEE Glass vs OEM&rsquo; zur Verbesserung der Industrieeffizienz","datePublished":"2026-03-06T12:24:13+00:00","dateModified":"2026-06-08T17:06:44+00:00","mainEntityOfPage":{"@id":"https:\/\/teeptrak.com\/de\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/"},"wordCount":519,"publisher":{"@id":"https:\/\/teeptrak.com\/de\/#organization"},"articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/teeptrak.com\/de\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/","url":"https:\/\/teeptrak.com\/de\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/","name":"OEE Glass vs OEM | TeepTrak","isPartOf":{"@id":"https:\/\/teeptrak.com\/de\/#website"},"datePublished":"2026-03-06T12:24:13+00:00","dateModified":"2026-06-08T17:06:44+00:00","description":"Erfahren Sie den Unterschied zwischen OEE Glass und OEM. Optimieren Sie Ihre Industrieeffizienz mit praktischen Insights und bew\u00e4hrten Strategien.","breadcrumb":{"@id":"https:\/\/teeptrak.com\/de\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teeptrak.com\/de\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/teeptrak.com\/de\/verstehen-sie-oee-glass-vs-oem-zur-verbesserung-der-industrieeffizienz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/teeptrak.com\/de\/nouvelle-page-daccueil\/"},{"@type":"ListItem","position":2,"name":"Verstehen Sie &lsquo;OEE Glass vs OEM&rsquo; zur Verbesserung der Industrieeffizienz"}]},{"@type":"WebSite","@id":"https:\/\/teeptrak.com\/de\/#website","url":"https:\/\/teeptrak.com\/de\/","name":"TEEPTRAK","description":"Optimisez votre potentiel industriel","publisher":{"@id":"https:\/\/teeptrak.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teeptrak.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/teeptrak.com\/de\/#organization","name":"TEEPTRAK","url":"https:\/\/teeptrak.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/teeptrak.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/teeptrak.com\/wp-content\/uploads\/2023\/05\/cropped-Capture-decran-2023-05-04-112832.png","contentUrl":"https:\/\/teeptrak.com\/wp-content\/uploads\/2023\/05\/cropped-Capture-decran-2023-05-04-112832.png","width":512,"height":512,"caption":"TEEPTRAK"},"image":{"@id":"https:\/\/teeptrak.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/teeptrak\/","https:\/\/www.linkedin.com\/company\/teeptrakinternational\/"]},{"@type":"Person","@id":"https:\/\/teeptrak.com\/de\/#\/schema\/person\/04395f9a2aa972ad0105f0c9f2e3fca3","name":"Ravinder Singh","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g","caption":"Ravinder Singh"},"url":"https:\/\/teeptrak.com\/de\/author\/ravinder-teeptrak\/"}]}},"_links":{"self":[{"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/posts\/80234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/users\/384731"}],"replies":[{"embeddable":true,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/comments?post=80234"}],"version-history":[{"count":1,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/posts\/80234\/revisions"}],"predecessor-version":[{"id":102574,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/posts\/80234\/revisions\/102574"}],"wp:attachment":[{"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/media?parent=80234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/categories?post=80234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/tags?post=80234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}