{"id":77632,"date":"2026-03-06T10:42:00","date_gmt":"2026-03-06T10:42:00","guid":{"rendered":"https:\/\/teeptrak.com\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/"},"modified":"2026-07-20T08:11:40","modified_gmt":"2026-07-20T08:11:40","slug":"cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2","status":"publish","type":"post","link":"https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/","title":{"rendered":"CMMS-Integration mit OEE: Steigern Sie die Effizienz Ihrer Produktionslinien"},"content":{"rendered":"<p>In der heutigen Industriewelt ist die Verbesserung der Gesamtanlageneffektivit\u00e4t (OEE) eine Priorit\u00e4t f\u00fcr Fabriken, die ihre Leistung optimieren m\u00f6chten. Die Integration von CMMS (Computergest\u00fctztes Instandhaltungsmanagementsystem) mit OEE ist eine Schl\u00fcssell\u00f6sung zur Erreichung dieses Ziels. Diese Integration erm\u00f6glicht eine bessere Koordination zwischen pr\u00e4ventiver und korrektiver Wartung und reduziert damit unerwartete Ausfallzeiten. Das Ziel besteht darin, diese beiden Systeme zu synchronisieren, um die Verf\u00fcgbarkeit der Ausr\u00fcstung zu maximieren, Kosten zu senken und die Qualit\u00e4t der Endprodukte zu verbessern.<\/p>\n<p>H\u00e4ufige Ursachen f\u00fcr Funktionsst\u00f6rungen sind schlecht geplante Wartung und Informationssilos zwischen operativen Teams und Wartung. Dies wirkt sich direkt auf die TRS\/OEE aus, die durch ungeplante Ausfallzeiten oder ineffiziente Gesamtrendite sinken kann. Die Kosten steigen, w\u00e4hrend Produktivit\u00e4t und Qualit\u00e4t darunter leiden. Eine schlecht beherrschte Integration kann daher zu erheblichen Verlusten bei Fristen und Qualit\u00e4t f\u00fchren.<\/p>\n<p>Um diese Probleme zu l\u00f6sen, ist die Anwendung von Methoden zur kontinuierlichen Verbesserung wie Lean Management in Kombination mit fortgeschrittener Digitalisierung des Shop Floor entscheidend. Zu verfolgende Indikatoren sind Verf\u00fcgbarkeit, Leistung und Qualit\u00e4t. Tools wie TeepTrak erm\u00f6glichen die Echtzeit\u00fcberwachung von TRS\/OEE und liefern pr\u00e4zise Analysen und n\u00fctzliche Einblicke f\u00fcr informierte Entscheidungen. Die Verwendung eines integrierten CMMS erleichtert die Verfolgung von Wartungsarbeiten und richtet damit die Ziele von Wartung und Produktion f\u00fcr optimierte Ergebnisse aus.<\/p>\n<p>Betrachten Sie eine Produktionslinie in einer Fabrik f\u00fcr Konsumg\u00fcter, wo h\u00e4ufige Wartungsprobleme zu wiederholten Ausfallzeiten f\u00fchrten. Durch die Integration des CMMS mit der OEE-Verfolgung von TeepTrak konnte die Fabrik schnell die Ausr\u00fcstung identifizieren, die eine pr\u00e4ventive Wartung ben\u00f6tigte. Die Echtzeit\u00fcberwachung erm\u00f6glichte eine bessere Planung der Wartungsaufgaben und eine Reduzierung von 20% der ungeplanten Ausfallzeiten, was die TRS erheblich erh\u00f6hte.<\/p>\n<p>F\u00fcr diejenigen, die bereit sind, ihr Projekt zu starten, ist es wichtig, die Ziele klar zu definieren und geeignete Leistungsindikatoren einzuf\u00fchren. Entscheiden Sie sich f\u00fcr L\u00f6sungen wie TeepTrak, die die Digitalisierung und die Steuerung der kontinuierlichen Verbesserung auf dem Shop Floor erleichtern. Die Vereinbarung eines strukturierten Plans, der mit Quick Wins beginnt, erm\u00f6glicht es Ihnen, schnelle Verbesserungen zu beobachten und damit die Grundlagen f\u00fcr ein langfristiges TRS\/OEE-Projekt zu schaffen.<\/p>\n<h3><strong>FAQ<\/strong><\/h3>\n<h4><strong>Frage 1: Welche Auswirkung hat die CMMS-Integration auf die OEE?<\/strong><\/h4>\n<p>Die Integration des CMMS mit der OEE verbessert die Koordination zwischen Wartungs- und Produktionsteams, reduziert ungeplante Ausfallzeiten und erh\u00f6ht die Verf\u00fcgbarkeit der Ausr\u00fcstung.<\/p>\n<h4><strong>Frage 2: Wo sollte man anfangen, um das CMMS mit der OEE zu integrieren?<\/strong><\/h4>\n<p>Beginnen Sie, indem Sie Ihre Leistungsziele klar definieren und Leistungsindikatoren ausw\u00e4hlen. W\u00e4hlen Sie dann eine L\u00f6sung wie TeepTrak, um die Echtzeit\u00fcberwachung von TRS\/OEE zu erleichtern.<\/p>\n<h4><strong>Frage 3: Was sind die Vorteile einer guten CMMS-OEE-Integration?<\/strong><\/h4>\n<p>Eine effektive Integration f\u00fchrt zu besserer Wartungsplanung, geringeren Kosten f\u00fcr Ausfallzeiten, verbesserter Produktqualit\u00e4t und einer gesamten Steigerung der Betriebseffizienz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Integrieren Sie OEE mit CMMS, um die Effizienz von Produktionslinien zu verbessern. Dieser vollst\u00e4ndige Leitfaden f\u00fcr Industrieleiter.<\/p>\n","protected":false},"author":384731,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_meta-robots-noindex":"","_yoast_wpseo_canonical":"https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien\/","_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","ai_seo_title":"CMMS OEE Integration | TeepTrak","ai_meta_description":"CMMS mit OEE integrieren und Produktionseffizienz steigern. Optimieren Sie Ihre Produktionslinien jetzt mit TeepTrak.","ai_focus_keyword":"cmms oee integration","footnotes":""},"categories":[7],"tags":[],"class_list":["post-77632","post","type-post","status-publish","format-standard","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CMMS OEE Integration | TeepTrak<\/title>\n<meta name=\"description\" content=\"CMMS mit OEE integrieren und Produktionseffizienz steigern. Optimieren Sie Ihre Produktionslinien jetzt mit TeepTrak.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CMMS OEE Integration | TeepTrak\" \/>\n<meta property=\"og:description\" content=\"CMMS mit OEE integrieren und Produktionseffizienz steigern. Optimieren Sie Ihre Produktionslinien jetzt mit TeepTrak.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/\" \/>\n<meta property=\"og:site_name\" content=\"TEEPTRAK\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-06T10:42:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-20T08:11:40+00:00\" \/>\n<meta name=\"author\" content=\"Ravinder Singh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@teeptrak\" \/>\n<meta name=\"twitter:site\" content=\"@teeptrak\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ravinder Singh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\\\/\"},\"author\":{\"name\":\"Ravinder Singh\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#\\\/schema\\\/person\\\/f21d6b6f72156f94a635171b5c8f9c01\"},\"headline\":\"CMMS-Integration mit OEE: Steigern Sie die Effizienz Ihrer Produktionslinien\",\"datePublished\":\"2026-03-06T10:42:00+00:00\",\"dateModified\":\"2026-07-20T08:11:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\\\/\"},\"wordCount\":498,\"publisher\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#organization\"},\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\\\/\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\\\/\",\"name\":\"CMMS OEE Integration | TeepTrak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#website\"},\"datePublished\":\"2026-03-06T10:42:00+00:00\",\"dateModified\":\"2026-07-20T08:11:40+00:00\",\"description\":\"CMMS mit OEE integrieren und Produktionseffizienz steigern. Optimieren Sie Ihre Produktionslinien jetzt mit TeepTrak.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/teeptrak.com\\\/de\\\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/nouvelle-page-daccueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CMMS-Integration mit OEE: Steigern Sie die Effizienz Ihrer Produktionslinien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/\",\"name\":\"TEEPTRAK\",\"description\":\"Le logiciel OEE en temps r\u00e9el \u2014 l&#039;alternative n\u00b01 au MES\",\"publisher\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#organization\",\"name\":\"TeepTrak\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/teeptrak.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/TeepTrak_Logo-PNG-1-scaled.png\",\"contentUrl\":\"https:\\\/\\\/teeptrak.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/TeepTrak_Logo-PNG-1-scaled.png\",\"width\":2880,\"height\":528,\"caption\":\"TeepTrak\"},\"image\":{\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/teeptrak\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/teeptrak\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/teeptrakinternational\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@teeptrak\\\/videos\",\"https:\\\/\\\/www.instagram.com\\\/teeptrak\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/teeptrak.com\\\/de\\\/#\\\/schema\\\/person\\\/f21d6b6f72156f94a635171b5c8f9c01\",\"name\":\"Ravinder Singh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g\",\"caption\":\"Ravinder Singh\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CMMS OEE Integration | TeepTrak","description":"CMMS mit OEE integrieren und Produktionseffizienz steigern. Optimieren Sie Ihre Produktionslinien jetzt mit TeepTrak.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/","og_locale":"de_DE","og_type":"article","og_title":"CMMS OEE Integration | TeepTrak","og_description":"CMMS mit OEE integrieren und Produktionseffizienz steigern. Optimieren Sie Ihre Produktionslinien jetzt mit TeepTrak.","og_url":"https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/","og_site_name":"TEEPTRAK","article_published_time":"2026-03-06T10:42:00+00:00","article_modified_time":"2026-07-20T08:11:40+00:00","author":"Ravinder Singh","twitter_card":"summary_large_image","twitter_creator":"@teeptrak","twitter_site":"@teeptrak","twitter_misc":{"Verfasst von":"Ravinder Singh","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/#article","isPartOf":{"@id":"https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/"},"author":{"name":"Ravinder Singh","@id":"https:\/\/teeptrak.com\/de\/#\/schema\/person\/f21d6b6f72156f94a635171b5c8f9c01"},"headline":"CMMS-Integration mit OEE: Steigern Sie die Effizienz Ihrer Produktionslinien","datePublished":"2026-03-06T10:42:00+00:00","dateModified":"2026-07-20T08:11:40+00:00","mainEntityOfPage":{"@id":"https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/"},"wordCount":498,"publisher":{"@id":"https:\/\/teeptrak.com\/de\/#organization"},"articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/","url":"https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/","name":"CMMS OEE Integration | TeepTrak","isPartOf":{"@id":"https:\/\/teeptrak.com\/de\/#website"},"datePublished":"2026-03-06T10:42:00+00:00","dateModified":"2026-07-20T08:11:40+00:00","description":"CMMS mit OEE integrieren und Produktionseffizienz steigern. Optimieren Sie Ihre Produktionslinien jetzt mit TeepTrak.","breadcrumb":{"@id":"https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/teeptrak.com\/de\/cmms-integration-mit-oee-steigern-sie-die-effizienz-ihrer-produktionslinien-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/teeptrak.com\/de\/nouvelle-page-daccueil\/"},{"@type":"ListItem","position":2,"name":"CMMS-Integration mit OEE: Steigern Sie die Effizienz Ihrer Produktionslinien"}]},{"@type":"WebSite","@id":"https:\/\/teeptrak.com\/de\/#website","url":"https:\/\/teeptrak.com\/de\/","name":"TEEPTRAK","description":"Le logiciel OEE en temps r\u00e9el \u2014 l&#039;alternative n\u00b01 au MES","publisher":{"@id":"https:\/\/teeptrak.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teeptrak.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/teeptrak.com\/de\/#organization","name":"TeepTrak","url":"https:\/\/teeptrak.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/teeptrak.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/teeptrak.com\/wp-content\/uploads\/2026\/07\/TeepTrak_Logo-PNG-1-scaled.png","contentUrl":"https:\/\/teeptrak.com\/wp-content\/uploads\/2026\/07\/TeepTrak_Logo-PNG-1-scaled.png","width":2880,"height":528,"caption":"TeepTrak"},"image":{"@id":"https:\/\/teeptrak.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/teeptrak","https:\/\/www.linkedin.com\/company\/teeptrak\/","https:\/\/www.linkedin.com\/company\/teeptrakinternational\/","https:\/\/www.youtube.com\/@teeptrak\/videos","https:\/\/www.instagram.com\/teeptrak\/"]},{"@type":"Person","@id":"https:\/\/teeptrak.com\/de\/#\/schema\/person\/f21d6b6f72156f94a635171b5c8f9c01","name":"Ravinder Singh","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/afa004471ac2dcd20a0bfe626e1cfd4d06876c592f2b766fca708c3d717a3d13?s=96&d=mm&r=g","caption":"Ravinder Singh"}}]}},"_links":{"self":[{"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/posts\/77632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/users\/384731"}],"replies":[{"embeddable":true,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/comments?post=77632"}],"version-history":[{"count":1,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/posts\/77632\/revisions"}],"predecessor-version":[{"id":103032,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/posts\/77632\/revisions\/103032"}],"wp:attachment":[{"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/media?parent=77632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/categories?post=77632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teeptrak.com\/de\/wp-json\/wp\/v2\/tags?post=77632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}